{"id":3714,"date":"2012-11-26T02:30:18","date_gmt":"2012-11-26T01:30:18","guid":{"rendered":"http:\/\/sciencetonnante.wordpress.com\/?p=3714"},"modified":"2012-11-26T02:30:18","modified_gmt":"2012-11-26T01:30:18","slug":"du-theoreme-du-nid-dabeille-a-la-conjecture-de-kelvin","status":"publish","type":"post","link":"https:\/\/scienceetonnante.com\/blog\/2012\/11\/26\/du-theoreme-du-nid-dabeille-a-la-conjecture-de-kelvin\/","title":{"rendered":"Du th\u00e9or\u00e8me du nid d&rsquo;abeille \u00e0 la conjecture de Kelvin"},"content":{"rendered":"<p style=\"text-align:justify;\"><a href=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/kelvin-pavage-300-171.png\"><img decoding=\"async\" class=\"alignleft size-full wp-image-3719 lazyload\" title=\"Kelvin pavage 300-171\" alt=\"\" data-src=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/kelvin-pavage-300-171.png\" height=\"171\" width=\"300\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/171;\" \/><\/a>En math\u00e9matiques, il existe quelques probl\u00e8mes tr\u00e8s simples \u00e0 \u00e9noncer mais incroyablement difficiles \u00e0 r\u00e9soudre. C&rsquo;est particuli\u00e8rement vrai en arithm\u00e9tique, et j&rsquo;ai d\u00e9j\u00e0 eu l&rsquo;occasion d&rsquo;\u00e9crire des billets sur la conjecture de Goldbach (<a title=\"La conjecture de\u00a0Goldbach\" href=\"https:\/\/scienceetonnante.com\/blog\/2010\/09\/13\/la-conjecture-de-goldbach\/\">ici<\/a>) et sur celle de Syracuse (<a title=\"La conjecture de\u00a0Syracuse\" href=\"https:\/\/scienceetonnante.com\/blog\/2011\/06\/27\/la-conjecture-de-syracuse\/\">l\u00e0<\/a>).<\/p>\n<p style=\"text-align:justify;\">Aujourd&rsquo;hui, nous allons voir qu&rsquo;en g\u00e9om\u00e9trie aussi, il existe des conjectures qu&rsquo;un coll\u00e9gien peut comprendre mais sur lesquelles les meilleurs math\u00e9maticiens du monde se cassent les dents. Et comme la g\u00e9om\u00e9trie est partout autour de nous, cela va nous permettre de faire <strong>un tour dans le monde des abeilles et celui des bulles de savon<\/strong>.<!--more--><\/p>\n<h3 style=\"text-align:justify;\">Un probl\u00e8me de pavage<\/h3>\n<p style=\"text-align:justify;\">C&rsquo;est d\u00e9cid\u00e9, vous allez refaire le carrelage de votre cuisine ! Vous vous rendez donc dans votre magasin de bricolage pr\u00e9f\u00e9r\u00e9 pour examiner les diff\u00e9rents mod\u00e8les disponibles. Il y a de tout : carr\u00e9s, rectangles, hexagones, triangles, mais aussi des formes plus compliqu\u00e9es comme des pavages \u00e0 la Escher. Le vendeur vous pr\u00e9cise que quel que soit le mod\u00e8le, le carreau fait toujours la m\u00eame surface. Comment choisir ?<\/p>\n<p style=\"text-align:justify;\"><a href=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/pavages.png\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-3721 lazyload\" title=\"pavages\" alt=\"\" data-src=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/pavages.png\" height=\"240\" width=\"600\" data-srcset=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/pavages.png 600w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/pavages-300x120.png 300w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/240;\" \/><\/a><\/p>\n<p style=\"text-align:justify;\">Pour ma part, je suis assez nul pour faire les joints. Si vous \u00eates comme moi, vous allez choisir le carreau qui donne le moins de joints \u00e0 faire, et c&rsquo;est <strong>celui dont le p\u00e9rim\u00e8tre est le plus petit<\/strong>. Mais quelle est donc la forme g\u00e9om\u00e9trique qui pour une surface donn\u00e9e poss\u00e8de le p\u00e9rim\u00e8tre le plus petit ? La r\u00e9ponse est connue depuis longtemps : il s&rsquo;agit du disque. Mais vous voyez bien qu&rsquo;avec des disques on ne peut pas faire un carrelage ! Il nous faut donc trouver <strong>la forme g\u00e9om\u00e9trique qui poss\u00e8de le plus petit p\u00e9rim\u00e8tre, et qui permet de paver une surface<\/strong>.<\/p>\n<p style=\"text-align:justify;\">L\u00e0 aussi la r\u00e9ponse est connue depuis l&rsquo;antiquit\u00e9 : <strong>il s&rsquo;agit de l&rsquo;hexagone r\u00e9gulier<\/strong>. Enfin, je dis \u00ab\u00a0la r\u00e9ponse est connue\u00a0\u00bb, mais en deux mill\u00e9naires, personne n&rsquo;avait r\u00e9ussi \u00e0 le d\u00e9montrer vraiment ! Et il a fallut attendre 1999 pour que le math\u00e9maticien Thomas Hales fournisse une preuve rigoureuse de ce r\u00e9sultat. Un bel exemple d&rsquo;une conjecture tr\u00e8s simple qui a r\u00e9sist\u00e9 \u00e0 des g\u00e9n\u00e9rations de math\u00e9maticiens.<\/p>\n<p style=\"text-align:justify;\">Bref, c&rsquo;est donc le carrelage avec des hexagones qui vous permet de limiter au maximum la quantit\u00e9 de joints.<\/p>\n<h3 style=\"text-align:justify;\"><a href=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/nids-dabeille.jpg\"><img decoding=\"async\" class=\"size-full wp-image-3723 alignright lazyload\" title=\"Close up view of the working bees on honeycells.\" alt=\"\" data-src=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/nids-dabeille.jpg\" height=\"375\" width=\"250\" data-srcset=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/nids-dabeille.jpg 250w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/nids-dabeille-200x300.jpg 200w\" data-sizes=\"(max-width: 250px) 100vw, 250px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 250px; --smush-placeholder-aspect-ratio: 250\/375;\" \/><\/a>Les hexagones dans la nature<\/h3>\n<p style=\"text-align:justify;\">La nature fait souvent bien les choses, et c&rsquo;est donc sans surprise que le pavage par des hexagones se retrouve chez nos amis les b\u00eates, et notamment par l&rsquo;exemple bien connu des alv\u00e9oles des nids d&rsquo;abeilles.<\/p>\n<p style=\"text-align:justify;\">De m\u00eame que cette forme permet de minimiser les joints de carrelage, elle permet de limiter la quantit\u00e9 de cire a utiliser pour cr\u00e9er les alv\u00e9oles. Le fait que le pavage hexagonal soit le meilleur est d&rsquo;ailleurs maintenant connu comme <strong>le th\u00e9or\u00e8me du nid d&rsquo;abeille<\/strong>.<\/p>\n<p style=\"text-align:justify;\">Est-ce \u00e0 dire que les abeilles ont r\u00e9ussi \u00e0 r\u00e9soudre un probl\u00e8me de g\u00e9om\u00e9trie tr\u00e8s compliqu\u00e9 ? Pour Darwin, il s&rsquo;agit plut\u00f4t d&rsquo;un effet de s\u00e9lection naturelle : les abeilles r\u00e9alisant les structures les plus \u00e9conomes sont celles qui ont \u00e9t\u00e9 s\u00e9lectionn\u00e9es par l&rsquo;\u00e9volution.<\/p>\n<p style=\"text-align:justify;\">Mais <a href=\"http:\/\/webinet.blogspot.com\/2010\/09\/lois-physiques1-abeilles-0.html\" target=\"_blank\" rel=\"noopener\">comme nous l&rsquo;explique Xochipilli<\/a> sur son blog le Webinet des curiosit\u00e9s, l&rsquo;explication est peut \u00eatre encore plus simple. On sait que si on ne cherche pas \u00e0 cr\u00e9er un pavage, alors la forme de plus petit p\u00e9rim\u00e8tre est le disque. Et <strong>si on juxtapose des disques et qu&rsquo;on les d\u00e9forme pour les forcer \u00e0 se toucher, on obtient assez naturellement un pavage hexagonal<\/strong> ! Alors, les abeilles, pas si g\u00e9niales que \u00e7a ?<\/p>\n<h3>Et en 3 dimensions ? Le probl\u00e8me de Kelvin<\/h3>\n<p style=\"text-align:justify;\">Maintenant que l&rsquo;on connait la forme de plus petit p\u00e9rim\u00e8tre qui permet de remplir une surface, on peut passer \u00e0 la question sup\u00e9rieure : <strong>quelle est le pavage de l&rsquo;espace qui poss\u00e8de la plus petite surface ?<\/strong> Pensez-vous que ce soit le cube ? Non, ce serait trop simple !<\/p>\n<p style=\"text-align:justify;\"><a href=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/truncated_octahedron.gif\"><img decoding=\"async\" class=\"alignright size-full wp-image-3726 lazyload\" title=\"truncated_octahedron\" alt=\"\" data-src=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/truncated_octahedron.gif\" height=\"180\" width=\"180\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 180px; --smush-placeholder-aspect-ratio: 180\/180;\" \/><\/a>Le physicien britannique Lord Kelvin s&rsquo;\u00e9tait pos\u00e9 cette question au XIX\u00e8me si\u00e8cle, et avait propos\u00e9 sa solution : pour lui, le meilleur pavage est celui qu&rsquo;on obtient avec <strong>l&rsquo;octa\u00e8dre tronqu\u00e9<\/strong>. Comme le montre l&rsquo;image ci-contre, il s&rsquo;agit d&rsquo;un volume poss\u00e9dant 14 faces dont 8 hexagones et 6 carr\u00e9s. Toutefois Kelvin n&rsquo;a pas su montrer que cette forme \u00e9tait la meilleure, mais il croyait ferme \u00e0 son r\u00e9sultat : <strong>cette affirmation est donc devenue la conjecture de Kelvin<\/strong>. Le pavage qui en r\u00e9sulte est repr\u00e9sent\u00e9 dans l&rsquo;image d&rsquo;en-t\u00eate de ce billet.<\/p>\n<p style=\"text-align:justify;\">Mais pour trouver la forme optimale en 3 dimensions, est-ce qu&rsquo;on ne pourrait pas s&rsquo;inspirer de ce que font les abeilles en 2 dimensions ? Eh bien si ! Et vous allez voir que pour cela <strong>il ne faut pas regarder du c\u00f4t\u00e9 des abeilles, mais plut\u00f4t du c\u00f4t\u00e9 de la bi\u00e8re<\/strong> !<\/p>\n<h3>Les mousses, des pavages en 3 dimensions<\/h3>\n<p style=\"text-align:justify;\"><a href=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/bulles-mousse.jpg\"><img decoding=\"async\" class=\"alignright  wp-image-3728 lazyload\" title=\"bulles mousse\" alt=\"\" data-src=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/bulles-mousse.jpg?w=300\" height=\"180\" width=\"240\" data-srcset=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/bulles-mousse.jpg 410w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/bulles-mousse-300x225.jpg 300w\" data-sizes=\"(max-width: 240px) 100vw, 240px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 240px; --smush-placeholder-aspect-ratio: 240\/180;\" \/><\/a>Nous l&rsquo;avons vu pr\u00e9c\u00e9demment, une mani\u00e8re naturelle de trouver la forme hexagonale, c&rsquo;est de partir de cercles juxtapos\u00e9s que l&rsquo;on d\u00e9forme. Si on veut faire pareil en 3 dimensions, <strong>on peut partir de sph\u00e8res juxtapos\u00e9es, et les d\u00e9former pour qu&rsquo;elles se touchent<\/strong>. Et c&rsquo;est justement ce qui se passe dans une mousse !<\/p>\n<p style=\"text-align:justify;\">En effet quand des bulles se forment dans un liquide, elles sont initialement sph\u00e9riques. Puis elles se touchent et se d\u00e9forment pour donner des poly\u00e8dres qui remplissent l&rsquo;espace en essayant de minimiser leur surface. Donc pour savoir si Kelvin avait raison, allons donc observer des mousses.<\/p>\n<p style=\"text-align:justify;\">C&rsquo;est justement ce qu&rsquo;a fait le botaniste Edwin Matzke en 1946 : il a fabriqu\u00e9 quelques litres de mousse dont les bulles poss\u00e9daient toutes le m\u00eame volume, et il a observ\u00e9 au microscope la forme des bulles. Et <strong>parmi les milliers de bulles ainsi examin\u00e9es, il n&rsquo;en a pas trouv\u00e9 une seule ayant la forme de l&rsquo;octa\u00e8dre tronqu\u00e9 de Kelvin<\/strong> ! Au contraire, il a not\u00e9 que les bulles poss\u00e9daient 13 ou 14 faces, et le plus souvent des faces pentagonales, alors que l&rsquo;octa\u00e8dre tronqu\u00e9 ne poss\u00e8de que des hexagones et des carr\u00e9s. Il a ensuite fallut attendre 1955 pour qu&rsquo;un autre botaniste, John Dodd, parvienne \u00e0 faire la premi\u00e8re photo d&rsquo;une bulle ayant la forme de Kelvin !<\/p>\n<p style=\"text-align:justify;\">Bref, Kelvin a peut-\u00eatre propos\u00e9 une forme optimale, mais contrairement au nid d&rsquo;abeille, la nature ne semble pas tr\u00e8s press\u00e9e de l&rsquo;adopter ! L&rsquo;argument m\u00e9canique propos\u00e9 par Xochipilli pour les nids d&rsquo;abeilles ne semble donc pas fonctionner en 3 dimensions !<\/p>\n<h3>Le contre-exemple de Weaire-Phelan<\/h3>\n<p style=\"text-align:justify;\"><a href=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/weaire-phelan.png\"><img decoding=\"async\" class=\"alignright size-full wp-image-3733 lazyload\" title=\"weaire-phelan\" alt=\"\" data-src=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/weaire-phelan.png\" height=\"252\" width=\"250\" data-srcset=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/weaire-phelan.png 250w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/weaire-phelan-150x150.png 150w\" data-sizes=\"(max-width: 250px) 100vw, 250px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 250px; --smush-placeholder-aspect-ratio: 250\/252;\" \/><\/a>En 1994, les choses en \u00e9taient toujours l\u00e0 quand &#8211; coup de th\u00e9atre ! &#8211;\u00a0 le physicien irlandais Denis Weaire et son \u00e9tudiant Robert Phelan finissent par trouver <strong>un contre-exemple \u00e0 la conjecture de Kelvin<\/strong>. Ils ont en effet trouv\u00e9 un pavage poss\u00e9dant une surface plus petite que celle avec l&rsquo;octa\u00e8dre tronqu\u00e9 de Kelvin. L&rsquo;am\u00e9lioration n&rsquo;est pas d\u00e9mentielle, seulement 0.3%, mais \u00e7a montre quand m\u00eame que Kelvin avait tort !<\/p>\n<p style=\"text-align:justify;\">Voyons un peu la forme trouv\u00e9 par Weaire et Phelan, ou plut\u00f4t les formes, car <strong>leur pavage est compos\u00e9 de 2 \u00e9l\u00e9ments de volume identique<\/strong> : l&rsquo;un poss\u00e8de 12 faces et l&rsquo;autre 14, les faces \u00e9tant des hexagones ou des pentagones.Vous pouvez admirer ci-contre la structure correspondante.<\/p>\n<p style=\"text-align:justify;\">A ce jour, Weaire et Phelan d\u00e9tiennent toujours le record, mais <strong>il n&rsquo;existe toujours pas de preuve math\u00e9matique que cette structure soit la meilleure possible<\/strong>. D&rsquo;ailleurs les recherches continuent, et un jeune chercheur italien, Ruggero Gabbrielli, a r\u00e9cemment r\u00e9ussi \u00e0 trouver un autre contre-exemple, moins bon que Weaire-Phelan mais\u00a0 quand m\u00eame meilleur que Kelvin. Au d\u00e9but de l&rsquo;ann\u00e9e 2012, il a \u00e9galement r\u00e9alis\u00e9 exp\u00e9rimentalement la premi\u00e8re mousse de Weaire-Phelan.<\/p>\n<p style=\"text-align:justify;\">Enfin cet \u00e9trange objet math\u00e9matique inspire aussi les designers, puisque le Water Cube, la piscine des Jeux Olympiques de P\u00e9kin en 2008, a \u00e9t\u00e9 r\u00e9alis\u00e9 sur le mod\u00e8le de la structure de Weaire-Phelan !<\/p>\n<p><a href=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/water_cube1.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-3732 lazyload\" title=\"water_cube\" alt=\"\" data-src=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/water_cube1.jpg\" height=\"299\" width=\"450\" data-srcset=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/water_cube1.jpg 450w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/water_cube1-300x199.jpg 300w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/water_cube1-270x180.jpg 270w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/water_cube1-370x245.jpg 370w\" data-sizes=\"(max-width: 450px) 100vw, 450px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 450px; --smush-placeholder-aspect-ratio: 450\/299;\" \/><\/a><\/p>\n<h3><em>Pour aller plus loin&#8230;<\/em><\/h3>\n<p style=\"text-align:justify;\"><em>Suite aux investigations de Matzke dans les mousses r\u00e9elles, plusieurs chercheurs se sont demand\u00e9s pourquoi la bulle en forme de cellule de Kelvin \u00e9tait si rare, alors qu&rsquo;elle est cens\u00e9e \u00eatre optimale. En 1961, Williams a propos\u00e9 une explication : il a construit un autre poly\u00e8dre \u00e0 14 faces (on dit un tetrakaideca\u00e8dre) qui est une variante de celui de Kelvin, et qui poss\u00e8de des faces pentagonales. Cette cellule de Williams semble \u00eatre la forme privil\u00e9gi\u00e9e qu&rsquo;adoptent les bulles dans un mousse faite de bulles monodisperses. La transformation de la cellule de Kelvin \u00e0 celle de Williams est donn\u00e9e ci-dessous<\/em><\/p>\n<p style=\"text-align:justify;\"><a href=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/800px-tetrakai-williams.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-3738 lazyload\" title=\"800px-Tetrakai - Williams\" alt=\"\" data-src=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/800px-tetrakai-williams.jpg\" height=\"194\" width=\"600\" data-srcset=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/800px-tetrakai-williams.jpg 800w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/800px-tetrakai-williams-300x97.jpg 300w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/11\/800px-tetrakai-williams-768x249.jpg 768w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/194;\" \/><\/a><\/p>\n<p style=\"text-align:justify;\"><em>Enfin l&rsquo;histoire de la d\u00e9monstration du th\u00e9or\u00e8me du nid d&rsquo;abeille par T.Hales est assez int\u00e9ressante. Ce dernier est \u00e9galement l&rsquo;auteur de la premi\u00e8re preuve de la conjecture de Kepler &#8211; dont je vous parlerai un autre jour &#8211; et qui porte sur la mani\u00e8re optimale d&#8217;empiler des sph\u00e8res. L\u00e0 aussi il s&rsquo;agit d&rsquo;un r\u00e9sultat tr\u00e8s simple, mais la d\u00e9monstration a du attendre des si\u00e8cles. Et la preuve de T. Hales est absolument monstrueuse ! Elle s&rsquo;\u00e9tale sur 250 pages et 8 publications, traite plus de 5000 cas diff\u00e9rents (dont un a n\u00e9cessit\u00e9 une th\u00e8se enti\u00e8re), et fait un usage intensif de programmes informatiques dont les entr\u00e9es et sorties totalisent 3 giga-octets de donn\u00e9es. Le papier a \u00e9t\u00e9 soumis en 1998 \u00e0 Annals of Mathematics, et accept\u00e9 seulement en 2005, apr\u00e8s que les 12 r\u00e9ferr\u00e9s aient d\u00e9cid\u00e9 d&rsquo;abandonner. Bref, une des d\u00e9monstrations les plus ardues de l&rsquo;histoire des math\u00e9matiques ! Apr\u00e8s ce travail de titan, Denis Weaire conseille \u00e0 Thomas Hales de s&rsquo;int\u00e9resser \u00e0 la conjecture du nid d&rsquo;abeille. \u00ab\u00a0Given its celebrated history, it seems worth a try.\u00a0\u00bb lui dit-il. Hales s&rsquo;imagine en reprendre pour 10 ans,\u00a0 et l\u00e0 suprise ! Il torche l&rsquo;affaire en 6 mois et seulement 20 pages de d\u00e9monstration ! Ce qui lui fait dire \u00ab\u00a0In contrast with the years of forced labor that gave the proof of the Kepler Conjecture, I felt as if I had won a lottery.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align:justify;\">\n","protected":false},"excerpt":{"rendered":"<p>En math\u00e9matiques, il existe quelques probl\u00e8mes tr\u00e8s simples \u00e0 \u00e9noncer mais incroyablement difficiles \u00e0 r\u00e9soudre. C&rsquo;est particuli\u00e8rement vrai en arithm\u00e9tique, et j&rsquo;ai d\u00e9j\u00e0 eu l&rsquo;occasion d&rsquo;\u00e9crire des billets sur la conjecture de Goldbach (ici) et sur celle de Syracuse (l\u00e0). Aujourd&rsquo;hui, nous allons voir qu&rsquo;en g\u00e9om\u00e9trie aussi, il existe des conjectures qu&rsquo;un coll\u00e9gien peut comprendre<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[58],"class_list":{"0":"post-3714","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-mathematiques","7":"tag-geometrie"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/posts\/3714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/comments?post=3714"}],"version-history":[{"count":0,"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/posts\/3714\/revisions"}],"wp:attachment":[{"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/media?parent=3714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/categories?post=3714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/tags?post=3714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}