{"id":3187,"date":"2012-06-18T00:01:09","date_gmt":"2012-06-17T22:01:09","guid":{"rendered":"http:\/\/sciencetonnante.wordpress.com\/?p=3187"},"modified":"2012-06-18T00:01:09","modified_gmt":"2012-06-17T22:01:09","slug":"la-chasse-aux-arcs-en-ciel-episode-ii","status":"publish","type":"post","link":"https:\/\/scienceetonnante.com\/blog\/2012\/06\/18\/la-chasse-aux-arcs-en-ciel-episode-ii\/","title":{"rendered":"La chasse aux arcs-en-ciel, \u00e9pisode II"},"content":{"rendered":"<p style=\"text-align:justify;\"><a href=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/05\/double-alaskan-rainbow.jpg\"><img decoding=\"async\" class=\"alignleft size-medium wp-image-3138 lazyload\" title=\"Double-alaskan-rainbow\" data-src=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/05\/double-alaskan-rainbow.jpg?w=300\" alt=\"\" width=\"300\" height=\"157\" data-srcset=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/05\/double-alaskan-rainbow.jpg 1919w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/05\/double-alaskan-rainbow-300x158.jpg 300w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/05\/double-alaskan-rainbow-1024x538.jpg 1024w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/05\/double-alaskan-rainbow-768x403.jpg 768w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/05\/double-alaskan-rainbow-1536x807.jpg 1536w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2012\/05\/double-alaskan-rainbow-1200x630.jpg 1200w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/157;\" \/><\/a>Dans mon billet d&rsquo;il y a quelques semaines, je vous ai propos\u00e9 de partir \u00e0 <a title=\"La chasse aux\u00a0arcs-en-ciel\" href=\"https:\/\/scienceetonnante.com\/blog\/2012\/05\/21\/la-chasse-aux-arcs-en-ciel\/\">la chasse aux arcs-en-ciel<\/a>. J&rsquo;ai notamment mentionn\u00e9 que l&rsquo;arc appara\u00eet sous un angle d&rsquo;environ 42\u00b0 par rapport \u00e0 l&rsquo;axe qui relie le soleil \u00e0 l&rsquo;observateur.<\/p>\n<p style=\"text-align:justify;\">Il se trouve qu&rsquo;en \u00e9crivant ce r\u00e9sultat, je me suis dit qu&rsquo;il devait d\u00e9couler de mani\u00e8re \u00e9vidente de la loi de Descartes appliqu\u00e9e \u00e0 l&rsquo;int\u00e9rieur de la goutte, un truc du genre arccos de 1\/n o\u00f9 n est l&rsquo;indice de r\u00e9fraction de l&rsquo;eau qui forme les gouttes. Mais en scientifique fain\u00e9ant et peu rigoureux, je n&rsquo;ai pas v\u00e9rifi\u00e9&#8230;<!--more--><\/p>\n<p style=\"text-align:justify;\">Mal m&rsquo;en a pris, car <a href=\"http:\/\/pourquoilecielestbleu.cafe-sciences.org\/\" target=\"_blank\" rel=\"noopener\">MrPourquoi<\/a> a commenc\u00e9 \u00e0 me titiller en me disant que \u00e7a n&rsquo;\u00e9tait pas du tout imm\u00e9diat \u00e0 d\u00e9montrer. Persuad\u00e9 du bien fond\u00e9 de ma croyance, j&rsquo;ai entrepris de retrouver le 42\u00b0 avec pour seuls outils un caf\u00e9, un crayon et un bout de papier. Et ce fut un \u00e9chec ! En effet je pensais na\u00efvement que l&rsquo;angle entre le rayon incident et le rayon sortant \u00e9tait toujours de 42\u00b0. Eh bien pas du tout !<\/p>\n<p style=\"text-align:justify;\"><a href=\"http:\/\/www.ac-nice.fr\/clea\/lunap\/html\/ArcEnCiel\/57-arc2.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignright lazyload\" title=\"Angle de d\u00e9viation Arc en ciel\" data-src=\"http:\/\/www.ac-nice.fr\/clea\/lunap\/html\/ArcEnCiel\/57-arc2.jpg\" alt=\"\" width=\"450\" height=\"326\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 450px; --smush-placeholder-aspect-ratio: 450\/326;\" \/><\/a>On peut montrer (voir <a href=\"http:\/\/www.ac-nice.fr\/clea\/lunap\/html\/ArcEnCiel\/ArcApprof.html\" target=\"_blank\" rel=\"noopener\">ici<\/a>, je reproduis le sch\u00e9ma ci-contre) que l&rsquo;angle vaut en r\u00e9alit\u00e9 A = 4r &#8211; 2i o\u00f9 i est l&rsquo;angle incident par rapport \u00e0 la normale de la surface de la goutte, et r est l&rsquo;angle r\u00e9fract\u00e9 \u00e0 l&rsquo;int\u00e9rieur de la goutte.<\/p>\n<p style=\"text-align:justify;\">Par la loi de Descartes l&rsquo;angle r est reli\u00e9 \u00e0 l&rsquo;angle i par <em><span style=\"color:#0000ff;\">sin i = n sin r<\/span><\/em>, o\u00f9 n est l&rsquo;indice de r\u00e9fraction de l&rsquo;eau (environ 1.33). Donc l&rsquo;angle de d\u00e9viation A peut valoir tout et n&rsquo;importe quoi, ou presque. Mais alors, pourquoi 42\u00b0 ?<\/p>\n<p style=\"text-align:justify;\">En fait, comme l&rsquo;explique tr\u00e8s bien <a href=\"http:\/\/pourquoilecielestbleu.cafe-sciences.org\/articles\/la-physique-des-arcs-en-ciel\/\" target=\"_blank\" rel=\"noopener\">MrPourquoi dans le billet qu&rsquo;il vient de publier<\/a>, il existe un maximum de cet angle de d\u00e9viation, pour lequel on a en plus une concentration de rayons (allez voir ses sch\u00e9mas !!)<\/p>\n<p style=\"text-align:justify;\">Pour trouver ce maximum, on peut \u00e9crire l&rsquo;angle de d\u00e9viation A=4r-2i uniquement en fonction de i gr\u00e2ce \u00e0 la formule de Descartes, on r\u00e9cup\u00e8re<\/p>\n<p style=\"text-align:center;\">\\(4 \\arcsin((1\/n)\\sin(i)) -2i \\)<\/p>\n<p>On peut en chercher le maximum analytiquement en d\u00e9rivant et en annulant la d\u00e9riv\u00e9e. Pour ma part, j&rsquo;ai <a href=\"http:\/\/www.wolframalpha.com\/input\/?i=maximum+of+4*arcsin%28%281%2Fn%29*sin%28x%29%29-2x+for+n%3D1.33\" target=\"_blank\" rel=\"noopener\">na\u00efvement demand\u00e9 \u00e0 Wolfram Alpha<\/a> qui me sort un maximum valant 0.742 radians, soit 42\u00b0 ! Wolfram Alpha c&rsquo;est quand m\u00eame cool !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans mon billet d&rsquo;il y a quelques semaines, je vous ai propos\u00e9 de partir \u00e0 la chasse aux arcs-en-ciel. J&rsquo;ai notamment mentionn\u00e9 que l&rsquo;arc appara\u00eet sous un angle d&rsquo;environ 42\u00b0 par rapport \u00e0 l&rsquo;axe qui relie le soleil \u00e0 l&rsquo;observateur. Il se trouve qu&rsquo;en \u00e9crivant ce r\u00e9sultat, je me suis dit qu&rsquo;il devait d\u00e9couler de<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[73],"class_list":{"0":"post-3187","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-physique","7":"tag-optique"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/posts\/3187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/comments?post=3187"}],"version-history":[{"count":0,"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/posts\/3187\/revisions"}],"wp:attachment":[{"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/media?parent=3187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/categories?post=3187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/tags?post=3187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}