{"id":2481,"date":"2011-12-19T00:01:11","date_gmt":"2011-12-18T23:01:11","guid":{"rendered":"http:\/\/sciencetonnante.wordpress.com\/?p=2481"},"modified":"2011-12-19T00:01:11","modified_gmt":"2011-12-18T23:01:11","slug":"leffet-noix-du-bresil","status":"publish","type":"post","link":"https:\/\/scienceetonnante.com\/blog\/2011\/12\/19\/leffet-noix-du-bresil\/","title":{"rendered":"L&rsquo;effet \u00ab\u00a0Noix du Br\u00e9sil\u00a0\u00bb"},"content":{"rendered":"<p style=\"text-align:justify;\"><a href=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2011\/12\/brazilnuteffect300.jpg\"><img decoding=\"async\" class=\"size-full wp-image-2483 alignleft lazyload\" title=\"brazilnuteffect300\" data-src=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2011\/12\/brazilnuteffect300.jpg\" alt=\"\" width=\"300\" height=\"187\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/187;\" \/><\/a>Puisque les f\u00eates approchent, penchons-nous sur un sujet festif : les g\u00e2teaux ap\u00e9ritifs ! Parmi ceux-ci, les m\u00e9langes de noix pr\u00e9sentent un ph\u00e9nom\u00e8ne physique tout \u00e0 fait intriguant : <strong>quand la boite a \u00e9t\u00e9 bien secou\u00e9e, les noix les plus grosses se retrouvent toutes \u00e0 la surface du m\u00e9lange<\/strong>.<\/p>\n<p style=\"text-align:justify;\">Ce ph\u00e9nom\u00e8ne est appel\u00e9 \u00ab <strong>effet Noix du Br\u00e9sil<\/strong> \u00bb, du nom des noix les plus grosses de ces m\u00e9langes. Et il n\u2019en finit pas d\u2019intriguer les physiciens, qui rivalisent d\u2019explications, de simulations et d\u2019exp\u00e9riences pour en comprendre la nature profonde.<!--more--><\/p>\n<h3 style=\"text-align:justify;\">Tout d\u2019abord, observons l\u2019effet<\/h3>\n<p style=\"text-align:justify;\">Pour recr\u00e9er l\u2019effet \u00ab Noix du Br\u00e9sil \u00bb, vous pouvez bien s\u00fbr acheter un paquet de g\u00e2teaux ap\u00e9ritifs. Mais pour cette fois, j\u2019ai choisi un cas plus simple : un bocal, de la semoule et une grosse balle en caoutchouc. On place la balle au fond du bocal de semoule, on tape dessus, et\u2026un film vaut mieux qu\u2019un long discours !<\/p>\n<p style=\"text-align:justify;\">[youtube=http:\/\/www.youtube.com\/watch?v=SKvQzVFg27Q]<\/p>\n<p style=\"text-align:justify;\">Et voil\u00e0 ! En quelques coups la grosse balle est remont\u00e9e en surface, exactement comme les noix du Br\u00e9sil dans les paquets de g\u00e2teaux ap\u00e9ritifs.<\/p>\n<p style=\"text-align:justify;\">Dans les milieux constitu\u00e9s de grains (dits <strong>milieux granulaires<\/strong>), on observe ce que les physiciens appellent une <strong>s\u00e9gr\u00e9gation par la taille<\/strong> : les objets les plus gros se retrouvent en surface et les plus petits au fond. Et ce m\u00eame si la densit\u00e9 des gros objets est plus \u00e9lev\u00e9e que celle des petits !<\/p>\n<p style=\"text-align:justify;\">Pour essayer de comprendre l\u2019effet \u00ab Noix du Br\u00e9sil \u00bb, plusieurs explications sont en concurrence. Voyons ensemble les deux plus connues.<\/p>\n<h3 style=\"text-align:justify;\">Une premi\u00e8re explication possible : l\u2019effet tamis<\/h3>\n<p style=\"text-align:justify;\">Pour expliquer la remont\u00e9e des gros objets dans un milieu granulaire, on peut faire appel \u00e0 un m\u00e9canisme intuitif relativement simple. Quand on secoue le bocal, tous les grains sont soulev\u00e9s, et les petits peuvent se glisser dans les interstices, pour aller se placer sous les gros grains. L\u2019inverse \u00e9tant impossible (les gros ne passent sous les petits), au fur et \u00e0 mesure les gros objets remontent en surface et y demeurent. Le milieu granulaire se comporte donc comme un tamis qui laisse tomber les petites particules, mais pas les grosses.<\/p>\n<p style=\"text-align:justify;\">Ce m\u00e9canisme est repr\u00e9sent\u00e9 sur la figure ci-dessous.<\/p>\n<p style=\"text-align:justify;\"><a href=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2011\/12\/effet_tamis.png\"><img decoding=\"async\" class=\"size-full wp-image-2485 aligncenter lazyload\" title=\"effet_tamis\" data-src=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2011\/12\/effet_tamis.png\" alt=\"\" width=\"600\" height=\"186\" data-srcset=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2011\/12\/effet_tamis.png 751w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2011\/12\/effet_tamis-300x93.png 300w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/186;\" \/><\/a><\/p>\n<p style=\"text-align:justify;\">Cette explication intuitive para\u00eet assez naturelle; et \u00e0 la fin des ann\u00e9es 80, des simulations informatiques ont pu permettre de v\u00e9rifier cette hypoth\u00e8se num\u00e9riquement. La question semblait presque r\u00e9gl\u00e9e, mais en 1993 une \u00e9quipe de l\u2019universit\u00e9 de Chicago a propos\u00e9 une exp\u00e9rience montrant qu\u2019un autre ph\u00e9nom\u00e8ne plus subtil intervenait : la convection granulaire [1].<\/p>\n<h3 style=\"text-align:justify;\">Une deuxi\u00e8me explication : La convection granulaire<\/h3>\n<p style=\"text-align:justify;\">Pour arriver \u00e0 leur nouvelle explication, les chercheurs de l\u2019\u00e9quipe de S. Nagel se sont livr\u00e9s \u00e0 un travail fastidieux : le suivi pr\u00e9cis du d\u00e9placement des grains dans un bocal que l\u2019on secoue. Pour cela ils ont marqu\u00e9 les grains avec de l\u2019encre, et les ont suivis dans leurs d\u00e9placements au cours de l\u2019exp\u00e9rience (aujourd\u2019hui on le fait par IRM, mais c\u2019\u00e9tait il y a 20 ans\u2026)<\/p>\n<p style=\"text-align:justify;\"><a href=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2011\/12\/convection-granulaire.png\"><img decoding=\"async\" class=\"alignright size-full wp-image-2486 lazyload\" title=\"convection granulaire\" data-src=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2011\/12\/convection-granulaire.png\" alt=\"\" width=\"300\" height=\"157\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/157;\" \/><\/a>Ils ont alors observ\u00e9 dans le bocal un ph\u00e9nom\u00e8ne nouveau : tous les grains sont soumis \u00e0 un grand mouvement d\u2019ensemble, qui les fait <strong>remonter par le centre et descendre par les c\u00f4t\u00e9s<\/strong>.<\/p>\n<p style=\"text-align:justify;\">Ce type de d\u00e9placement (repr\u00e9sent\u00e9 \u00e0 gauche sur le sch\u00e9ma ci-contre) est appel\u00e9 <strong>convection granulaire<\/strong>, et rappelle les ph\u00e9nom\u00e8nes de convection qu\u2019on observe avec les fluides, comme dans l\u2019atmosph\u00e8re ou dans une casserole : l\u2019air chaud (ou l\u2019eau chaude) monte, se refroidit et descend par les c\u00f4t\u00e9s (voir la figure de droite sur le sch\u00e9ma).<\/p>\n<p style=\"text-align:justify;\">Le mouvement de convection granulaire dans le bocal peut alors expliquer l\u2019effet \u00ab Noix du Br\u00e9sil \u00bb : les grosses noix sont remont\u00e9es au centre par le mouvement de convection, mais sont trop grosses pour redescendre par le courant descendant qui s\u2019\u00e9tablit juste au bord des parois.<\/p>\n<p style=\"text-align:justify;\">En r\u00e9alit\u00e9, la largeur de la couche de grains qui redescend le long des parois d\u00e9pend de la forme et de la mani\u00e8re dont on tape. <strong>J\u2019ai pu reproduire ce ph\u00e9nom\u00e8ne avec ma semoule et ma balle en caoutchouc<\/strong>. Le film ci-dessous est en fait la fin et la continuation du film pr\u00e9c\u00e9dent. Vous allez voir la balle s\u2019enfoncer au bord, puis r\u00e9appara\u00eetre au centre !<\/p>\n<p style=\"text-align:justify;\">[youtube=http:\/\/www.youtube.com\/watch?v=idbsiSe6xk0]<\/p>\n<h3 style=\"text-align:justify;\">Manipuler la convection granulaire<\/h3>\n<p style=\"text-align:justify;\">L\u2019effet \u00ab Noix du Br\u00e9sil \u00bb a de nombreuses cons\u00e9quences naturelles (comme le fait bien connu des paysans que les gros cailloux remontent \u00e0 la surface d\u2019un champ) mais aussi plusieurs applications industrielles : le m\u00e9lange des noix bien s\u00fbr, mais aussi celui des c\u00e9r\u00e9ales, du b\u00e9ton, etc. Des chercheurs et des industriels se sont donc demand\u00e9s s&rsquo;il \u00e9tait possible de le limiter ou de le supprimer.<\/p>\n<p style=\"text-align:justify;\"><a href=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2011\/12\/slip_cone_convection.png\"><img decoding=\"async\" class=\"alignright size-medium wp-image-2488 lazyload\" title=\"slip_cone_convection\" data-src=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2011\/12\/slip_cone_convection.png?w=300\" alt=\"\" width=\"300\" height=\"236\" data-srcset=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2011\/12\/slip_cone_convection.png 967w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2011\/12\/slip_cone_convection-300x237.png 300w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2011\/12\/slip_cone_convection-768x606.png 768w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2011\/12\/slip_cone_convection-87x67.png 87w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/236;\" \/><\/a>Eh bien gr\u00e2ce \u00e0 leur compr\u00e9hension du ph\u00e9nom\u00e8ne par la convection granulaire, les chercheurs de Chicago ont pu construire des cas permettant de limiter voire carr\u00e9ment d\u2019inverser la convection granulaire.<\/p>\n<p style=\"text-align:justify;\">Par exemple en diminuant les frottements contre les parois, on peut supprimer le ph\u00e9nom\u00e8ne de descente des grains. Le sch\u00e9ma ci-contre montre une exp\u00e9rience qu\u2019ils ont r\u00e9alis\u00e9 [1] o\u00f9 la paroi de droite frotte beaucoup plus que la paroi de gauche : les grains descendent uniquement le long de la paroi de droite. Encore plus fort, en modifiant la g\u00e9om\u00e9trie du bocal, <strong>on peut inverser la convection granulaire<\/strong> : dans un c\u00f4ne renvers\u00e9 les grosses noix coulent au milieu et les petites remontent par les parois !<\/p>\n<h3 style=\"text-align:justify;\">Encore beaucoup de travail\u2026<\/h3>\n<p style=\"text-align:justify;\">Malgr\u00e9 ces d\u00e9couvertes dans des exp\u00e9riences bien contr\u00f4l\u00e9es, il existe encore de tr\u00e8s nombreuses zones d\u2019ombre sur les ph\u00e9nom\u00e8nes r\u00e9ellement en jeu dans l\u2019effet \u00ab Noix du Br\u00e9sil \u00bb. En voici une illustration \u00e9tonnante.<\/p>\n<p style=\"text-align:justify;\"><a href=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2011\/12\/vitesse_ascension.png\"><img decoding=\"async\" class=\"alignright size-full wp-image-2490 lazyload\" title=\"vitesse_ascension\" data-src=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2011\/12\/vitesse_ascension.png\" alt=\"\" width=\"222\" height=\"173\" data-srcset=\"https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2011\/12\/vitesse_ascension.png 222w, https:\/\/scienceetonnante.com\/blog\/wp-content\/uploads\/2011\/12\/vitesse_ascension-87x67.png 87w\" data-sizes=\"(max-width: 222px) 100vw, 222px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 222px; --smush-placeholder-aspect-ratio: 222\/173;\" \/><\/a>A priori, on peut penser que dans ce ph\u00e9nom\u00e8ne, l\u2019air ne joue aucun r\u00f4le. Il est notamment beaucoup moins dense que les grains. Et pourtant, S. Nagel et sa bande (toujours eux) ont montr\u00e9 que sous vide, le ph\u00e9nom\u00e8ne est sensiblement modifi\u00e9 [2].<\/p>\n<p style=\"text-align:justify;\">A pression atmosph\u00e9rique, ils ont constat\u00e9 que la vitesse d\u2019ascension des grosses particules d\u00e9pend de leur densit\u00e9, avec un maximum quand la densit\u00e9 des grosses est \u00e9gale \u00e0 la moiti\u00e9 de celle des petites. Mais sous vide, cette d\u00e9pendance dispara\u00eet ! Donc l\u2019air joue bien un r\u00f4le subtil dans la convection granulaire, via les frottements qu&rsquo;il peut imposer aux grains. L&rsquo;effet \u00ab\u00a0Noix du Br\u00e9sil\u00a0\u00bb est encore loin d&rsquo;avoir livr\u00e9 tous ses myst\u00e8res !<\/p>\n<p style=\"text-align:justify;\"><em>[1] S. Nagel et al., \u00ab\u00a0Vibration-indiced size separation in granular media : the convection connexion\u00a0\u00bb, Physical Review Letters, Vol. 70, N. 24 (1993) p3728.<\/em><\/p>\n<p style=\"text-align:justify;\"><em>[2] Matthias E. M\u00f6bius et al., \u201cThe Effect of Air on Granular Size Separation in a Vibrated Granular Bed\u201d, Phys. Rev. E 72, 011304, (2005) \/ <a href=\"http:\/\/arxiv.org\/abs\/cond-mat\/0502622\" target=\"_blank\" rel=\"noopener\">cond-mat\/0502622<\/a>.<\/em><\/p>\n<h3 style=\"text-align:justify;\"><em>Pour aller plus loin : quelques consid\u00e9rations thermodynamiques<\/em><\/h3>\n<p style=\"text-align:justify;\"><em>Le ph\u00e9nom\u00e8ne de s\u00e9gr\u00e9gation par la taille dans les milieux granulaires est assez intriguant. Dans un fluide normal, le fait de secouer provoque un m\u00e9lange et une homog\u00e9n\u00e9isation, donc une augmentation de l\u2019entropie. Dans les milieux granulaires, c\u2019est l\u2019inverse. Puisqu\u2019en secouant on s\u00e9pare les grains par taille, on fait diminuer l\u2019entropie !<\/em><\/p>\n<p style=\"text-align:justify;\"><em>Pour r\u00e9soudre ce paradoxe, il faut r\u00e9aliser que dans un syst\u00e8me comme celui-ci, on est tr\u00e8s tr\u00e8s loin des conditions de l\u2019\u00e9quilibre thermodynamique. Pour s\u2019en convaincre, on peut comparer les ordres de grandeur des \u00e9nergies mises en jeu.<\/em><\/p>\n<p style=\"text-align:justify;\"><em>Dans un gaz classique, le produit kT de la constante de Boltzmann par la temp\u00e9rature donne l\u2019ordre de grandeur de l\u2019\u00e9nergie d\u2019une particule du gaz. Dans le milieu granulaire, c\u2019est tr\u00e8s diff\u00e9rent. Si on regarde la variation de l\u2019\u00e9nergie potentielle de gravit\u00e9 d\u2019un grain qui tombe sur une hauteur \u00e9gale \u00e0 sa taille, on obtient mgd, o\u00f9 m est sa masse, g l\u2019acc\u00e9l\u00e9ration de la gravit\u00e9 et d son diam\u00e8tre.<\/em><\/p>\n<p style=\"text-align:justify;\"><em>Pour un grain de semoule, on trouve environ 10^-8 joules. Mais \u00e0 temp\u00e9rature ambiante, kT = 4.10^-21 joules ! Donc l\u2019\u00e9nergie du grain est beaucoup beaucoup plus \u00e9lev\u00e9e que l\u2019\u00e9nergie thermique, ce qui nous permet de comprendre qu\u2019on puisse se situer si loin de l\u2019\u00e9quilibre thermodynamique.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Puisque les f\u00eates approchent, penchons-nous sur un sujet festif : les g\u00e2teaux ap\u00e9ritifs ! Parmi ceux-ci, les m\u00e9langes de noix pr\u00e9sentent un ph\u00e9nom\u00e8ne physique tout \u00e0 fait intriguant : quand la boite a \u00e9t\u00e9 bien secou\u00e9e, les noix les plus grosses se retrouvent toutes \u00e0 la surface du m\u00e9lange. Ce ph\u00e9nom\u00e8ne est appel\u00e9 \u00ab effet<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[24],"class_list":{"0":"post-2481","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-physique","7":"tag-mecanique-des-fluides"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/posts\/2481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/comments?post=2481"}],"version-history":[{"count":0,"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/posts\/2481\/revisions"}],"wp:attachment":[{"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/media?parent=2481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/categories?post=2481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/scienceetonnante.com\/blog\/wp-json\/wp\/v2\/tags?post=2481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}